{"id":113,"count":1,"description":"<h1 style=\"text-align: center\">La FOSSE's chaire and Armchairs<\/h1>","link":"https:\/\/lafosse.ca\/en\/product-category\/chairs-and-armchairs\/","name":"Chairs and armchairs","slug":"chairs-and-armchairs","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":6,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Chairs and armchairs - Antiques<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lafosse.ca\/en\/product-category\/chairs-and-armchairs\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Chairs and armchairs - Antiques\" \/>\n<meta property=\"og:description\" content=\"La FOSSE&#8217;s chaire and Armchairs\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lafosse.ca\/en\/product-category\/chairs-and-armchairs\/\" \/>\n<meta property=\"og:site_name\" content=\"Antiques\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lafosse.ca\/wp-content\/uploads\/2023\/12\/Facebook_photo_couverture-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"824\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lafosse.ca\\\/en\\\/product-category\\\/chairs-and-armchairs\\\/\",\"url\":\"https:\\\/\\\/lafosse.ca\\\/en\\\/product-category\\\/chairs-and-armchairs\\\/\",\"name\":\"Archives des Chairs and armchairs - Antiques\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lafosse.ca\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lafosse.ca\\\/en\\\/product-category\\\/chairs-and-armchairs\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lafosse.ca\\\/en\\\/product-category\\\/chairs-and-armchairs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lafosse.ca\\\/en\\\/la-fosse\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chairs and armchairs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lafosse.ca\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/lafosse.ca\\\/en\\\/\",\"name\":\"Antiquit\u00e9s\",\"description\":\"An unusual antique store. The perfect place to find something out of the ordinary.\",\"publisher\":{\"@id\":\"https:\\\/\\\/lafosse.ca\\\/en\\\/#organization\"},\"alternateName\":\"La Fosse\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lafosse.ca\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lafosse.ca\\\/en\\\/#organization\",\"name\":\"La Fosse - Antiquit\u00e9s et objets insolites\",\"alternateName\":\"la Fosse\",\"url\":\"https:\\\/\\\/lafosse.ca\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lafosse.ca\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lafosse.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/logo_la-fosse_fond-fonce_grand-format-inverse-petit.jpg\",\"contentUrl\":\"https:\\\/\\\/lafosse.ca\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/logo_la-fosse_fond-fonce_grand-format-inverse-petit.jpg\",\"width\":700,\"height\":700,\"caption\":\"La Fosse - Antiquit\u00e9s et objets insolites\"},\"image\":{\"@id\":\"https:\\\/\\\/lafosse.ca\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LaFosseAntiquites\",\"https:\\\/\\\/www.instagram.com\\\/lafosse.ca\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/la-fosse-antiquites-et-objets-insolites\\\/?viewAsMember=true\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Chairs and armchairs - Antiques","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lafosse.ca\/en\/product-category\/chairs-and-armchairs\/","og_locale":"en_US","og_type":"article","og_title":"Archives des Chairs and armchairs - Antiques","og_description":"La FOSSE&#8217;s chaire and Armchairs","og_url":"https:\/\/lafosse.ca\/en\/product-category\/chairs-and-armchairs\/","og_site_name":"Antiques","og_image":[{"width":824,"height":315,"url":"https:\/\/lafosse.ca\/wp-content\/uploads\/2023\/12\/Facebook_photo_couverture-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lafosse.ca\/en\/product-category\/chairs-and-armchairs\/","url":"https:\/\/lafosse.ca\/en\/product-category\/chairs-and-armchairs\/","name":"Archives des Chairs and armchairs - Antiques","isPartOf":{"@id":"https:\/\/lafosse.ca\/en\/#website"},"breadcrumb":{"@id":"https:\/\/lafosse.ca\/en\/product-category\/chairs-and-armchairs\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/lafosse.ca\/en\/product-category\/chairs-and-armchairs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lafosse.ca\/en\/la-fosse\/"},{"@type":"ListItem","position":2,"name":"Chairs and armchairs"}]},{"@type":"WebSite","@id":"https:\/\/lafosse.ca\/en\/#website","url":"https:\/\/lafosse.ca\/en\/","name":"Antiquit\u00e9s","description":"An unusual antique store. The perfect place to find something out of the ordinary.","publisher":{"@id":"https:\/\/lafosse.ca\/en\/#organization"},"alternateName":"La Fosse","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lafosse.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lafosse.ca\/en\/#organization","name":"La Fosse - Antiquit\u00e9s et objets insolites","alternateName":"la Fosse","url":"https:\/\/lafosse.ca\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lafosse.ca\/en\/#\/schema\/logo\/image\/","url":"https:\/\/lafosse.ca\/wp-content\/uploads\/2022\/09\/logo_la-fosse_fond-fonce_grand-format-inverse-petit.jpg","contentUrl":"https:\/\/lafosse.ca\/wp-content\/uploads\/2022\/09\/logo_la-fosse_fond-fonce_grand-format-inverse-petit.jpg","width":700,"height":700,"caption":"La Fosse - Antiquit\u00e9s et objets insolites"},"image":{"@id":"https:\/\/lafosse.ca\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LaFosseAntiquites","https:\/\/www.instagram.com\/lafosse.ca\/","https:\/\/www.linkedin.com\/company\/la-fosse-antiquites-et-objets-insolites\/?viewAsMember=true"]}]}},"_links":{"self":[{"href":"https:\/\/lafosse.ca\/en\/wp-json\/wp\/v2\/product_cat\/113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lafosse.ca\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/lafosse.ca\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/lafosse.ca\/en\/wp-json\/wp\/v2\/product?product_cat=113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}